{"id":12,"date":"2018-07-31T12:15:26","date_gmt":"2018-07-31T09:15:26","guid":{"rendered":"https:\/\/xstore.8theme.com\/?page_id=3"},"modified":"2025-09-18T16:52:45","modified_gmt":"2025-09-18T13:52:45","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/dia24.eu\/it\/privacy-policy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"12\" class=\"elementor elementor-12\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24d6b1cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24d6b1cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-671c4de7\" data-id=\"671c4de7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e8796d elementor-widget elementor-widget-text-editor\" data-id=\"59e8796d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Politica sulla privacy<\/h2><p>dia24.eu (Societ\u00e0) \u00e8 il responsabile del trattamento dei dati personali.\u00a0<\/p><h3>Raccolta e utilizzo dei dati personali<\/h3><p>I dati personali sono dati che dia24.eu raccoglie per identificare o contattare una singola persona. I dati personali possono essere raccolti con il consenso del cliente nei seguenti modi:<\/p><ul><li>Dati di contatto: il cliente fornisce i dati di contatto, che includono il nome, l'indirizzo postale, il numero di telefono e l'indirizzo e-mail, utilizzando il nostro webshop.<\/li><li>Utilizzando il nostro sito web (dia24.eu) tramite i cookie<\/li><\/ul><p>I dati personali raccolti ci consentono di informare i clienti sui loro ordini, sulle modifiche ai dettagli dell'ordine e sulle nostre novit\u00e0.<br \/>I dati personali saranno utilizzati anche per la consegna della merce e per adempiere ai nostri obblighi nei confronti del cliente.<\/p><h3>Protezione dei dati personali<\/h3><p>dia24.eu prende tutte le precauzioni, comprese le misure amministrative, tecniche e fisiche per proteggere i dati personali dei clienti. I dati personali possono essere consultati e modificati solo da personale autorizzato.<\/p><h3>Sicurezza<\/h3><p>Tutti i dati personali divulgati nel corso della visita al nostro negozio web e dell'acquisto saranno trattati come informazioni riservate. dia24.eu utilizza canali di comunicazione sicuri e criptati con i gateway di pagamento e sul suo sito web.<\/p><h3>Modifiche all'Informativa sulla privacy<\/h3><p>Ci riserviamo il diritto di modificare la presente Informativa sulla privacy, se necessario. Accedendo al nostro sito web e utilizzandolo, presumiamo che lei abbia letto e accettato questa politica. In caso di ulteriori domande, la preghiamo di contattarci.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy policy dia24.eu (Company) is the processor of personal data.\u00a0 Collection and use of personal data Personal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/dia24.eu\/it\/privacy-policy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"dia24 \u2014 diabetic products and glucose sensors\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Privacy Policy \u2014 dia24\" \/>\n\t\t<meta property=\"og:description\" content=\"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dia24.eu\/it\/privacy-policy\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-31T09:15:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-18T13:52:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Privacy Policy \u2014 dia24\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dia24.eu\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#listItem\",\"name\":\"Privacy Policy\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#listItem\",\"position\":2,\"name\":\"Privacy Policy\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/#organization\",\"name\":\"dia24\",\"description\":\"diabetic products and glucose sensors\",\"url\":\"https:\\\/\\\/dia24.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dia24.eu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DIA24-Logo.svg\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#organizationLogo\",\"width\":375,\"height\":150},\"image\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#webpage\",\"url\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy \\u2014 dia24\",\"description\":\"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/privacy-policy\\\/#breadcrumblist\"},\"datePublished\":\"2018-07-31T12:15:26+03:00\",\"dateModified\":\"2025-09-18T16:52:45+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/dia24.eu\\\/it\\\/\",\"name\":\"dia24\",\"description\":\"diabetic products and glucose sensors\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Privacy Policy \u2014 dia24","description":"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and","canonical_url":"https:\/\/dia24.eu\/it\/privacy-policy\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dia24.eu\/it#listItem","position":1,"name":"Home","item":"https:\/\/dia24.eu\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#listItem","name":"Privacy Policy"}},{"@type":"ListItem","@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#listItem","position":2,"name":"Privacy Policy","previousItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/it#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/dia24.eu\/it\/#organization","name":"dia24","description":"diabetic products and glucose sensors","url":"https:\/\/dia24.eu\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/dia24.eu\/wp-content\/uploads\/2023\/03\/DIA24-Logo.svg","@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#organizationLogo","width":375,"height":150},"image":{"@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#webpage","url":"https:\/\/dia24.eu\/it\/privacy-policy\/","name":"Privacy Policy \u2014 dia24","description":"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/dia24.eu\/it\/#website"},"breadcrumb":{"@id":"https:\/\/dia24.eu\/it\/privacy-policy\/#breadcrumblist"},"datePublished":"2018-07-31T12:15:26+03:00","dateModified":"2025-09-18T16:52:45+03:00"},{"@type":"WebSite","@id":"https:\/\/dia24.eu\/it\/#website","url":"https:\/\/dia24.eu\/it\/","name":"dia24","description":"diabetic products and glucose sensors","inLanguage":"it-IT","publisher":{"@id":"https:\/\/dia24.eu\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"dia24 \u2014 diabetic products and glucose sensors","og:type":"article","og:title":"Privacy Policy \u2014 dia24","og:description":"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and","og:url":"https:\/\/dia24.eu\/it\/privacy-policy\/","article:published_time":"2018-07-31T09:15:26+00:00","article:modified_time":"2025-09-18T13:52:45+00:00","twitter:card":"summary_large_image","twitter:title":"Privacy Policy \u2014 dia24","twitter:description":"Privacy policydia24.eu (Company) is the processor of personal data. Collection and use of personal dataPersonal data is data that dia24.eu collects to identify or contact an individual person. Personal data may be collected with the consent of the customer in the following ways:Contact details: customer provides contact details, which include name, postal address, phone number and"},"aioseo_meta_data":{"post_id":"12","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-29 13:17:55","updated":"2025-09-18 13:55:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dia24.eu\/it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPrivacy Policy\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dia24.eu\/it"},{"label":"Privacy Policy","link":"https:\/\/dia24.eu\/it\/privacy-policy\/"}],"_links":{"self":[{"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":6,"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":15854,"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/pages\/12\/revisions\/15854"}],"wp:attachment":[{"href":"https:\/\/dia24.eu\/it\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}