{"id":7243,"date":"2023-02-08T18:52:15","date_gmt":"2023-02-08T16:52:15","guid":{"rendered":"https:\/\/dia24.eu\/?post_type=product&#038;p=7243"},"modified":"2025-05-29T18:48:36","modified_gmt":"2025-05-29T15:48:36","slug":"ketosens-blood-%ce%b2-ketone-test-strips-n10","status":"publish","type":"product","link":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/","title":{"rendered":"Benzile de testare a \u03b2-cetonei din s\u00e2nge KetoSens N10"},"content":{"rendered":"<p>Benzile de testare a \u03b2-cetonului din s\u00e2nge KetoSens sunt concepute pentru a fi utilizate cu <strong><a href=\"https:\/\/dia24.eu\/ro\/product\/caresens-dual-for-the-measurement-of-%ce%b2-ketones\/\">Glucometru dublu CareSens Dual<\/a><\/strong>.<br \/>\nBenzile de testare KetoSens v\u0103 permit s\u0103 m\u0103sura\u021bi rapid \u0219i u\u0219or nivelul de \u03b2-ceton\u0103 din s\u00e2nge. Tot ce ave\u021bi nevoie este o cantitate mic\u0103 de prob\u0103 de s\u00e2nge \u0219i pute\u021bi vedea rezultatele \u00een 8 secunde.<\/p>\n<p>Benzile de testare KetoSens sunt f\u0103r\u0103 cod \u0219i sunt de tip aspirator (aspir\u0103 singure o cantitate suficient\u0103 de s\u00e2nge).<\/p>\n<p>The <strong>cutia con\u021bine 10 benzi de testare<\/strong>, \u00eenvelite individual \u00een folie de aluminiu.<\/p>\n<p>Pentru utilizare NUMAI cu <strong><a href=\"https:\/\/dia24.eu\/ro\/product\/caresens-dual-for-the-measurement-of-%ce%b2-ketones\/\">CareSens Dual<\/a><\/strong> dispozitiv de m\u0103surare.<\/p>","protected":false},"excerpt":{"rendered":"<p>Benzile de testare a \u03b2-cetonului din s\u00e2nge KetoSens sunt concepute pentru a fi utilizate cu glucometrul CareSens Dual Glucometer.<\/p>","protected":false},"featured_media":7244,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"etheme_brands":[],"product_brand":[],"product_cat":[88,96],"product_tag":[],"class_list":["post-7243","product","type-product","status-publish","has-post-thumbnail","product_cat-accessories","product_cat-blood-glucose-meters","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ro_RO\" \/>\n\t\t<meta property=\"og:site_name\" content=\"dia24 \u2014 diabetic products and glucose sensors\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24\" \/>\n\t\t<meta property=\"og:description\" content=\"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-08T16:52:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-29T15:48:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24\" \/>\n\t\t<meta name=\"twitter:description\" content=\"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dia24.eu\\\/ro\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/#listItem\",\"name\":\"Accessories\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/#listItem\",\"position\":3,\"name\":\"Accessories\",\"item\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/blood-glucose-meters\\\/#listItem\",\"name\":\"Glucometers\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/blood-glucose-meters\\\/#listItem\",\"position\":4,\"name\":\"Glucometers\",\"item\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/blood-glucose-meters\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#listItem\",\"name\":\"KetoSens blood \\u03b2-ketone test strips N10\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/#listItem\",\"name\":\"Accessories\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#listItem\",\"position\":5,\"name\":\"KetoSens blood \\u03b2-ketone test strips N10\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/categorie-produs\\\/accessories\\\/blood-glucose-meters\\\/#listItem\",\"name\":\"Glucometers\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#itempage\",\"url\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/\",\"name\":\"KetoSens blood \\u03b2-ketone test strips N10 \\u2014 dia24\",\"description\":\"KetoSens blood \\u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.\",\"inLanguage\":\"ro-RO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dia24.eu\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ketoonide-mootmine-ketosens-testribad.png\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#mainImage\",\"width\":600,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#mainImage\"},\"datePublished\":\"2023-02-08T18:52:15+02:00\",\"dateModified\":\"2025-05-29T18:48:36+03:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/#organization\",\"name\":\"dia24\",\"description\":\"diabetic products and glucose sensors\",\"url\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dia24.eu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DIA24-Logo.svg\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#organizationLogo\",\"width\":375,\"height\":150},\"image\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/product\\\/ketosens-blood-%ce%b2-ketone-test-strips-n10\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/\",\"name\":\"dia24\",\"description\":\"diabetic products and glucose sensors\",\"inLanguage\":\"ro-RO\",\"publisher\":{\"@id\":\"https:\\\/\\\/dia24.eu\\\/ro\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24","description":"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.","canonical_url":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro#listItem","position":1,"name":"Home","item":"https:\/\/dia24.eu\/ro","nextItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/dia24.eu\/ro\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/#listItem","name":"Accessories"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/#listItem","position":3,"name":"Accessories","item":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/#listItem","name":"Glucometers"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/#listItem","position":4,"name":"Glucometers","item":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#listItem","name":"KetoSens blood \u03b2-ketone test strips N10"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/#listItem","name":"Accessories"}},{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#listItem","position":5,"name":"KetoSens blood \u03b2-ketone test strips N10","previousItem":{"@type":"ListItem","@id":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/#listItem","name":"Glucometers"}}]},{"@type":"ItemPage","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#itempage","url":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/","name":"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24","description":"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.","inLanguage":"ro-RO","isPartOf":{"@id":"https:\/\/dia24.eu\/ro\/#website"},"breadcrumb":{"@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/dia24.eu\/wp-content\/uploads\/2023\/02\/ketoonide-mootmine-ketosens-testribad.png","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#mainImage","width":600,"height":600},"primaryImageOfPage":{"@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#mainImage"},"datePublished":"2023-02-08T18:52:15+02:00","dateModified":"2025-05-29T18:48:36+03:00"},{"@type":"Organization","@id":"https:\/\/dia24.eu\/ro\/#organization","name":"dia24","description":"diabetic products and glucose sensors","url":"https:\/\/dia24.eu\/ro\/","logo":{"@type":"ImageObject","url":"https:\/\/dia24.eu\/wp-content\/uploads\/2023\/03\/DIA24-Logo.svg","@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#organizationLogo","width":375,"height":150},"image":{"@id":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/dia24.eu\/ro\/#website","url":"https:\/\/dia24.eu\/ro\/","name":"dia24","description":"diabetic products and glucose sensors","inLanguage":"ro-RO","publisher":{"@id":"https:\/\/dia24.eu\/ro\/#organization"}}]},"og:locale":"ro_RO","og:site_name":"dia24 \u2014 diabetic products and glucose sensors","og:type":"article","og:title":"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24","og:description":"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer.","og:url":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/","article:published_time":"2023-02-08T16:52:15+00:00","article:modified_time":"2025-05-29T15:48:36+00:00","twitter:card":"summary_large_image","twitter:title":"KetoSens blood \u03b2-ketone test strips N10 \u2014 dia24","twitter:description":"KetoSens blood \u03b2-ketone test strips are designed for use with the CareSens Dual Glucometer."},"aioseo_meta_data":{"post_id":"7243","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-29 13:19:46","updated":"2025-09-02 23:13:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dia24.eu\/ro\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dia24.eu\/ro\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/\" title=\"Accessories\">Accessories<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/\" title=\"Glucometers\">Glucometers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKetoSens blood \u03b2-ketone test strips N10\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dia24.eu\/ro"},{"label":"Shop","link":"https:\/\/dia24.eu\/ro\/shop\/"},{"label":"Accessories","link":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/"},{"label":"Glucometers","link":"https:\/\/dia24.eu\/ro\/categorie-produs\/accessories\/blood-glucose-meters\/"},{"label":"KetoSens blood \u03b2-ketone test strips N10","link":"https:\/\/dia24.eu\/ro\/product\/ketosens-blood-%ce%b2-ketone-test-strips-n10\/"}],"_links":{"self":[{"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product\/7243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/comments?post=7243"}],"version-history":[{"count":1,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product\/7243\/revisions"}],"predecessor-version":[{"id":7245,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product\/7243\/revisions\/7245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/media\/7244"}],"wp:attachment":[{"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/media?parent=7243"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/etheme_brands?post=7243"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product_brand?post=7243"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product_cat?post=7243"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dia24.eu\/ro\/wp-json\/wp\/v2\/product_tag?post=7243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}